{"id":2116,"date":"2018-03-14T14:43:42","date_gmt":"2018-03-14T11:43:42","guid":{"rendered":"https:\/\/mesaimalat.com.tr\/products\/"},"modified":"2024-03-01T16:54:37","modified_gmt":"2024-03-01T13:54:37","slug":"products","status":"publish","type":"page","link":"https:\/\/www.mesaimalat.com.tr\/en\/products\/","title":{"rendered":"Products"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section][vc_row][vc_column][vc_tta_accordion active_section=&#8221;1&#8243; el_class=&#8221;all-product-items-tabs&#8221;][vc_tta_section title=&#8221;Formwork Systems&#8221; tab_id=&#8221;1704199498508-c7a9db8e-cd41&#8243;]<div class=\"page-all-products-items\"><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/mktf\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>MKTF<\/h1>\n\t\t\t\t\t\t\t<h2>Modified Tunnel Formwork<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/MKTF-Tunel-Kalip-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/ertf\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>ERTF<\/h1>\n\t\t\t\t\t\t\t<h2>Modular Tunnel Formwork<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/ERTF-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/trtf\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>TRTF<\/h1>\n\t\t\t\t\t\t\t<h2>Classic Tunnel Formwork<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/TRTF-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/revola\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>REVOLA<\/h1>\n\t\t\t\t\t\t\t<h2>Framed Wall Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/1-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/frwf\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>FRWF<\/h1>\n\t\t\t\t\t\t\t<h2>Steel Wall Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/FRWF-perde-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/logica\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>LOGICA<\/h1>\n\t\t\t\t\t\t\t<h2>Framed Wall Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/logica-perde-3-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/h20p\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>H20P<\/h1>\n\t\t\t\t\t\t\t<h2>Wall Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/H20-perde-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/plexo\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>PLEXO<\/h1>\n\t\t\t\t\t\t\t<h2>Curved Wall Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/PLEXO-ahsap-perde-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/flexo\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>FLEXO<\/h1>\n\t\t\t\t\t\t\t<h2>Curved Steel Wall Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/FLEXO-celik-perde-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/logica-2\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>LOGICA<\/h1>\n\t\t\t\t\t\t\t<h2>Adjustable Column Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/logica-kolon-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/stilo\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>STILO<\/h1>\n\t\t\t\t\t\t\t<h2>Circular Steel Column Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/STILO-kolon-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/h20p-2\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>H20P<\/h1>\n\t\t\t\t\t\t\t<h2>Column Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/H20-kolon-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/forked-column\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>FORKED COLUMN<\/h1>\n\t\t\t\t\t\t\t<h2>Special Steel Faced Column Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/11\/Ozel-kolon-catal-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/pier\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>BRIDGE ABUTMENT<\/h1>\n\t\t\t\t\t\t\t<h2>Special Steel faced Column Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/pier-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/revola-2\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>REVOLA<\/h1>\n\t\t\t\t\t\t\t<h2>Adjustable Column Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/4-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/pier-2\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>PIER<\/h1>\n\t\t\t\t\t\t\t<h2>Special Steel Faced Column Form<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/11\/PIER-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/mesa-flex\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>MESA FLEX<\/h1>\n\t\t\t\t\t\t\t<h2>Shoring and Table Formwork System<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/MESA-FLEX-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/mesa-prop\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>MESA PROP<\/h1>\n\t\t\t\t\t\t\t<h2>Adjustable Prop and Table System<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/MESA-PROP-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/mesa-deck\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>MESA LOCK<\/h1>\n\t\t\t\t\t\t\t<h2>Cup lock Shoring System<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/CUPLOCK-0004.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/v-beam-bridge\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>V-Beam Bridge<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/V-kiris-kopru-prekast-0013.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/manhole\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Manhole-Chimney<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Baca-menhol-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/manhole-2\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Manhole<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Menhol-prekast-0013.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/retaining-wall\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Retaining Wall<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Ihata-duvari-prekast-0014.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/barrier\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Barrier<\/h1>\n\t\t\t\t\t\t\t<h2>Precast mold<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/bariyer-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/i-beam\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>I-Beam<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/I-kiris-prekast-0013.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/beam\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Beam<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Kiris-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/battery\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Battery<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Batarya-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/stairs\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Stairs<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Merdiven-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/vibrating-table\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Vibrating Table<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Vibrasyonlu-masa-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/vent\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Vent<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Menfez-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/stream-rehabilitation\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Stream Rehabilitation<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Dere-islah-prekast-0013.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/patterned-column\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Patterned Column<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Desenli-prekast-.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/pot\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Pot<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Saksi-prekast-.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/stadium\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Stadium<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Stadyum-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/factory-column\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Factory Column<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/fabrika-kolon-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Scaffolding Systems&#8221; tab_id=&#8221;1704199498515-738a6483-51ab&#8221;]<div class=\"page-all-products-items\"><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/mesa-al70\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>MESA AL70<\/h1>\n\t\t\t\t\t\t\t<h2>Framed Access Scaffolding<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/AL70-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/mesa-lock\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>MESA CUPLOCK<\/h1>\n\t\t\t\t\t\t\t<h2>Stair-Cup Type Facade \/ Working Scaffolding System<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/CUPLOCK-merdiven-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/mesa-safe\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>MESA SAFE<\/h1>\n\t\t\t\t\t\t\t<h2>Construction Safety System<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/MESA-SAFE-5.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/ksk\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>KSK<\/h1>\n\t\t\t\t\t\t\t<h2>Gable End Frame Platform<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/KSK-0001.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/16e\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>16E<\/h1>\n\t\t\t\t\t\t\t<h2>Stripping Platform<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/16E-0001.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Special Systems&#8221; tab_id=&#8221;1704199587134-856b70df-6890&#8243;]<div class=\"page-all-products-items\"><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/vcr\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>VCR<\/h1>\n\t\t\t\t\t\t\t<h2>Climbing System- Crane Lifted<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/VCR-0001.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/hcp\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>HCP<\/h1>\n\t\t\t\t\t\t\t<h2>Hydraulic Climbing System<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/HCP-0001.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/ctp\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>WRP<\/h1>\n\t\t\t\t\t\t\t<h2>Climbing Platform System<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/WRP-0001.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/wsp\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>WSP<\/h1>\n\t\t\t\t\t\t\t<h2>Wind Shield System<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/WSP-0001.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/tbm-segment-mould\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>TBM SEGMENT MOULD<\/h1>\n\t\t\t\t\t\t\t<h2>Underground TBM Tunnel Mold<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/Segment-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/slab-track-mould\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Slab Track Mould<\/h1>\n\t\t\t\t\t\t\t<h2>Rail Systems Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2020\/06\/1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/travelling-tunnel-form\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>NATM TUNNELS<\/h1>\n\t\t\t\t\t\t\t<h2>Travelling Tunnel Formwork<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2018\/01\/9.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/b07\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>B07<\/h1>\n\t\t\t\t\t\t\t<h2>Rail Systems Mold<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/10\/B07-travers-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/turnout-bearers\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>TURNOUT BEARERS<\/h1>\n\t\t\t\t\t\t\t<h2>Rail Systems Mold<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/10\/Makas-travers-4.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/heavy-haul\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>HEAVY HAUL<\/h1>\n\t\t\t\t\t\t\t<h2>Rail Systems Mold<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/10\/heavy-haul-travers-2.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/steel-construction\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>STEEL CONSTRUCTION<\/h1>\n\t\t\t\t\t\t\t<h2>Steel Structure Systems<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2019\/07\/Steel-Building-Frame.H03.2k-e1707200871324.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><\/div>[\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_section][vc_row][vc_column][vc_tta_accordion active_section=&#8221;1&#8243; el_class=&#8221;all-product-items-tabs&#8221;][vc_tta_section title=&#8221;Formwork Systems&#8221; tab_id=&#8221;1704199498508-c7a9db8e-cd41&#8243;][\/vc_tta_section][vc_tta_section title=&#8221;Scaffolding Systems&#8221; tab_id=&#8221;1704199498515-738a6483-51ab&#8221;][\/vc_tta_section][vc_tta_section title=&#8221;Special Systems&#8221; tab_id=&#8221;1704199587134-856b70df-6890&#8243;][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][\/vc_section]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":178,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"yst_prominent_words":[],"class_list":["post-2116","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/pages\/2116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/comments?post=2116"}],"version-history":[{"count":1,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/pages\/2116\/revisions"}],"predecessor-version":[{"id":11869,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/pages\/2116\/revisions\/11869"}],"wp:attachment":[{"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/media?parent=2116"}],"wp:term":[{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/yst_prominent_words?post=2116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}