{"id":2125,"date":"2018-03-14T16:01:12","date_gmt":"2018-03-14T13:01:12","guid":{"rendered":"https:\/\/mesaimalat.com.tr\/products\/formwork-systems\/precast-moulds\/"},"modified":"2018-03-14T16:01:12","modified_gmt":"2018-03-14T13:01:12","slug":"precast-moulds","status":"publish","type":"page","link":"https:\/\/www.mesaimalat.com.tr\/en\/products\/formwork-systems\/precast-moulds\/","title":{"rendered":"Precast Moulds"},"content":{"rendered":"<div class=\"page-all-products-items\"><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/v-beam-bridge\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>V-Beam Bridge<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/V-kiris-kopru-prekast-0013.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/manhole\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Manhole-Chimney<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Baca-menhol-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/manhole-2\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Manhole<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Menhol-prekast-0013.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/retaining-wall\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Retaining Wall<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Ihata-duvari-prekast-0014.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/barrier\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Barrier<\/h1>\n\t\t\t\t\t\t\t<h2>Precast mold<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/bariyer-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/i-beam\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>I-Beam<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/I-kiris-prekast-0013.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/beam\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Beam<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Kiris-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/battery\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Battery<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Batarya-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/stairs\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Stairs<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Merdiven-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/vibrating-table\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Vibrating Table<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Vibrasyonlu-masa-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/vent\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Vent<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Menfez-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/stream-rehabilitation\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Stream Rehabilitation<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Dere-islah-prekast-0013.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/patterned-column\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Patterned Column<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Desenli-prekast-.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/pot\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Pot<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/Saksi-prekast-.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/stadium\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Stadium<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2024\/01\/Stadyum-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><div class=\"all-project-grid-item\"><a href=\"https:\/\/www.mesaimalat.com.tr\/en\/urun\/factory-column\/\">\n                        <div class=\"project-title\">\n\t\t\t\t\t\t\t<h1>Factory Column<\/h1>\n\t\t\t\t\t\t\t<h2>Precast Mould<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"project-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mesaimalat.com.tr\/wp-content\/uploads\/2023\/12\/fabrika-kolon-prekast-0012.png\" alt=\"\">\n\t\t\t\t\t\t<\/div><\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"V-Beam Bridge Precast Mould Manhole-Chimney Precast Mould Manhole Precast Mould Retaining Wall Precast Mould Barrier Precast mold I-Beam Precast Mould Beam Precast Mould Battery Precast Mould Stairs Precast Mould Vibrating Table Precast Mould Vent Precast Mould Stream Rehabilitation Precast Mould Patterned Column Precast Mould Pot Precast Mould Stadium Precast Mould Factory Column Precast Mould","protected":false},"author":1,"featured_media":0,"parent":2121,"menu_order":230,"comment_status":"closed","ping_status":"closed","template":"template-urunsistemler.php","meta":{"ngg_post_thumbnail":0,"footnotes":""},"yst_prominent_words":[],"class_list":["post-2125","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/pages\/2125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/comments?post=2125"}],"version-history":[{"count":0,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/pages\/2125\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/pages\/2121"}],"wp:attachment":[{"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/media?parent=2125"}],"wp:term":[{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.mesaimalat.com.tr\/en\/wp-json\/wp\/v2\/yst_prominent_words?post=2125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}